{"id":778,"date":"2017-01-31T08:55:52","date_gmt":"2017-01-31T06:55:52","guid":{"rendered":"http:\/\/pyrga.org\/?post_type=portfolio&#038;p=778\/"},"modified":"2017-02-02T10:11:01","modified_gmt":"2017-02-02T08:11:01","slug":"photo-gallery","status":"publish","type":"portfolio","link":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/","title":{"rendered":"Photo Gallery"},"content":{"rendered":"<div id=\"6a048d7d7e68c\" class=\"gg_gallery_wrap gg_true_gallery gg_standard_gallery gid_862 gg_hidden_ol gg_ol_bottom_mode gg_main_ol_show_on_h \" data-gg_ol=\"default\"  rel=\"862\" data-nores-txt=\"No images found\">              <div class=\"gg_loader\">            <div class=\"ggl_1\"><\/div>            <div class=\"ggl_2\"><\/div>            <div class=\"ggl_3\"><\/div>            <div class=\"ggl_4\"><\/div>        <\/div>  <div class=\"gg_container\"><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_22.jpg\" data-gg-title=\"photo_gallery_22\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"0\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_c1654ecd72400b49915bae1786da9954.jpg\" alt=\"photo_gallery_22\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_22.jpg\" alt=\"photo_gallery_22\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_21.jpg\" data-gg-title=\"photo_gallery_21\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"1\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_6e58c7fc586de283eae076b3a6a580a7.jpg\" alt=\"photo_gallery_21\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_21.jpg\" alt=\"photo_gallery_21\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_20.jpg\" data-gg-title=\"photo_gallery_20\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"2\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_828e79271013385d1e36aca0380c6506.jpg\" alt=\"photo_gallery_20\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_20.jpg\" alt=\"photo_gallery_20\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_19.jpg\" data-gg-title=\"photo_gallery_19\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"3\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_43add7fcd08799abf7a46b7d94d20fd1.jpg\" alt=\"photo_gallery_19\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_19.jpg\" alt=\"photo_gallery_19\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_18.jpg\" data-gg-title=\"photo_gallery_18\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"4\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_6ce76b9d7748bbebb9bf41979d905228.jpg\" alt=\"photo_gallery_18\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_18.jpg\" alt=\"photo_gallery_18\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_17.jpg\" data-gg-title=\"photo_gallery_17\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"5\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_7b425eace2979ec64fd10ab9d005d789.jpg\" alt=\"photo_gallery_17\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_17.jpg\" alt=\"photo_gallery_17\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_16.jpg\" data-gg-title=\"photo_gallery_16\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"6\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_547d7126f1eadb1b75c30d8ac58e9bc4.jpg\" alt=\"photo_gallery_16\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_16.jpg\" alt=\"photo_gallery_16\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_15.jpg\" data-gg-title=\"photo_gallery_15\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"7\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_fd3d4d146c986adccfa8449bc11307a0.jpg\" alt=\"photo_gallery_15\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_15.jpg\" alt=\"photo_gallery_15\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_14.jpg\" data-gg-title=\"photo_gallery_14\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"8\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_876ddb81d5707b8f43a9967fd1cc4a38.jpg\" alt=\"photo_gallery_14\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_14.jpg\" alt=\"photo_gallery_14\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_13.jpg\" data-gg-title=\"photo_gallery_13\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"9\" rel=\"862\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/pyrga.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_eb38806eb4905b478c822e26def412a3.jpg\" alt=\"photo_gallery_13\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/pyrga.org\/wp-content\/uploads\/photo_gallery_13.jpg\" alt=\"photo_gallery_13\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><\/div><div class=\"gg_paginate gg_pag_light\" gg-random=\"0\" data-gg-totpages=\"3\"><div class=\"gg_standard_pag \"><div class=\"gg_nav_left gg_prev_page gg_pag_disabled\"><i><\/i><\/div><div class=\"gg_nav_mid\"><div>page <span>1<\/span> of 3<\/div><\/div><div class=\"gg_nav_right gg_next_page \"><i><\/i><\/div><\/div><\/div><div style=\"clear: both;\"><\/div><\/div><script type=\"text\/javascript\"> (function($) {             \"use strict\";                          if(typeof(gg_pag_vars) == \"undefined\") {                window.gg_pag_vars = {};            }            gg_pag_vars[\"6a048d7d7e68c\"] = {                per_page: 10,                pagination_sys: \"standard\",                watermark : 0,                random_trail : \"false\",                wp_gall_hash: \"\"            };        })(jQuery);<\/script><script type=\"text\/javascript\">     (function($) {         \"use strict\";              $(document).ready(function($) {             if(typeof(gg_galleries_init) == \"function\") {                gg_galleries_init(\"6a048d7d7e68c\");             }        });    })(jQuery);<\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1050,"template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[34],"class_list":["post-778","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-what-to-see"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Photo Gallery - \u03a0\u03c5\u03c1\u03b3\u03ac<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Photo Gallery - \u03a0\u03c5\u03c1\u03b3\u03ac\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"\u03a0\u03c5\u03c1\u03b3\u03ac\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-02T08:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pyrga.org\/wp-content\/uploads\/banner_gallery.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"220\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pyrga.org\\\/en\\\/portfolio-item\\\/photo-gallery\\\/\",\"url\":\"https:\\\/\\\/pyrga.org\\\/en\\\/portfolio-item\\\/photo-gallery\\\/\",\"name\":\"Photo Gallery - \u03a0\u03c5\u03c1\u03b3\u03ac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pyrga.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pyrga.org\\\/en\\\/portfolio-item\\\/photo-gallery\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pyrga.org\\\/en\\\/portfolio-item\\\/photo-gallery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pyrga.org\\\/wp-content\\\/uploads\\\/banner_gallery.jpg\",\"datePublished\":\"2017-01-31T06:55:52+00:00\",\"dateModified\":\"2017-02-02T08:11:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pyrga.org\\\/en\\\/portfolio-item\\\/photo-gallery\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pyrga.org\\\/en\\\/portfolio-item\\\/photo-gallery\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pyrga.org\\\/en\\\/portfolio-item\\\/photo-gallery\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pyrga.org\\\/wp-content\\\/uploads\\\/banner_gallery.jpg\",\"contentUrl\":\"https:\\\/\\\/pyrga.org\\\/wp-content\\\/uploads\\\/banner_gallery.jpg\",\"width\":220,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pyrga.org\\\/en\\\/portfolio-item\\\/photo-gallery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pyrga.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photo Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pyrga.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/pyrga.org\\\/en\\\/\",\"name\":\"\u03a0\u03c5\u03c1\u03b3\u03ac\",\"description\":\"Pyrga\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pyrga.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Photo Gallery - \u03a0\u03c5\u03c1\u03b3\u03ac","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/","og_locale":"en_US","og_type":"article","og_title":"Photo Gallery - \u03a0\u03c5\u03c1\u03b3\u03ac","og_url":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/","og_site_name":"\u03a0\u03c5\u03c1\u03b3\u03ac","article_modified_time":"2017-02-02T08:11:01+00:00","og_image":[{"width":220,"height":150,"url":"https:\/\/pyrga.org\/wp-content\/uploads\/banner_gallery.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/","url":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/","name":"Photo Gallery - \u03a0\u03c5\u03c1\u03b3\u03ac","isPartOf":{"@id":"https:\/\/pyrga.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/#primaryimage"},"image":{"@id":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/#primaryimage"},"thumbnailUrl":"https:\/\/pyrga.org\/wp-content\/uploads\/banner_gallery.jpg","datePublished":"2017-01-31T06:55:52+00:00","dateModified":"2017-02-02T08:11:01+00:00","breadcrumb":{"@id":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/#primaryimage","url":"https:\/\/pyrga.org\/wp-content\/uploads\/banner_gallery.jpg","contentUrl":"https:\/\/pyrga.org\/wp-content\/uploads\/banner_gallery.jpg","width":220,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/pyrga.org\/en\/portfolio-item\/photo-gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pyrga.org\/en\/"},{"@type":"ListItem","position":2,"name":"Photo Gallery"}]},{"@type":"WebSite","@id":"https:\/\/pyrga.org\/en\/#website","url":"https:\/\/pyrga.org\/en\/","name":"\u03a0\u03c5\u03c1\u03b3\u03ac","description":"Pyrga","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pyrga.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/portfolio\/778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/portfolio\/778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/media\/1050"}],"wp:attachment":[{"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/tags?post=778"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/pyrga.org\/en\/wp-json\/wp\/v2\/portfolio_entries?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}